{"id":814,"date":"2018-03-13T13:11:53","date_gmt":"2018-03-13T12:11:53","guid":{"rendered":"http:\/\/fwg-woellstadt.de\/?p=814"},"modified":"2020-10-24T13:13:57","modified_gmt":"2020-10-24T11:13:57","slug":"falscher-microsoft-mitarbeiter","status":"publish","type":"post","link":"http:\/\/fwg-woellstadt.de\/index.php\/2018\/03\/13\/falscher-microsoft-mitarbeiter\/","title":{"rendered":"Falscher Microsoft-Mitarbeiter"},"content":{"rendered":"\n<p>+++ vom Polizei-Pressedienst +++<br><br>Wie dieser Tage bekannt wurde, hatte sich im Februar ein angeblicher Microsoft-Mitarbeiter bei einer Seniorin in W\u00f6llstadt gemeldet. An vier Tagen w\u00e4hlte der Betr\u00fcger insgesamt siebenmal die Nummer der Frau und redete in englischer Sprache auf sie ein. Laut Polizei handelte es sich offenbar um den Versuch, die Frau davon zu \u00fcberzeugen, dass es auf ihrem Computer einen Virus gebe. \u00bbDarauf folgt in der Regel das Angebot, diesen zu entfernen, wozu diverse Eingaben erforderlich sind. Betr\u00fcger, die mit dieser Masche arbeiten, erlangen hierdurch Zugriff auf den Computer ihrer Opfer und t\u00e4tigen in der Folge Buchungen \u00fcber deren Konten und Bestellungen. Die smarte W\u00f6llst\u00e4dterin ging ihm aber nicht auf den Leim. Sie beendete das Telefonat mit den Worten: \u203aI never speak about my Computer on the phone!\u2039\u00ab, schreibt die Polizei in einer Pressemitteilung. Seitdem habe sich der Mann nicht mehr gemeldet. Die Polizei warnt davor, Ausk\u00fcnfte \u00fcber pers\u00f6nliche Daten via Telefon zu geben. \u00bbMicrosoft-Mitarbeiter melden sich nicht telefonisch. Im Zweifel \u2013 legen Sie einfach auf!\u00ab<\/p>\n\n\n\n<p>Bitte auch Familienangeh\u00f6rigen, Nachbarn und Bekannten weitergeben, die nicht bei Facebook und vielleicht nicht ganz so vertraut mit dem PC sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>+++ vom Polizei-Pressedienst +++ Wie dieser Tage bekannt wurde, hatte sich im Februar ein angeblicher Microsoft-Mitarbeiter bei einer Seniorin in W\u00f6llstadt gemeldet. An vier Tagen w\u00e4hlte der Betr\u00fcger insgesamt siebenmal die Nummer der Frau und <a class=\"mh-excerpt-more\" href=\"http:\/\/fwg-woellstadt.de\/index.php\/2018\/03\/13\/falscher-microsoft-mitarbeiter\/\" title=\"Falscher Microsoft-Mitarbeiter\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":815,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[2],"tags":[75],"class_list":["post-814","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gemeindepolitik","tag-sicherheit"],"_links":{"self":[{"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/posts\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/comments?post=814"}],"version-history":[{"count":1,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions"}],"predecessor-version":[{"id":816,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions\/816"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/media\/815"}],"wp:attachment":[{"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/media?parent=814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/categories?post=814"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fwg-woellstadt.de\/index.php\/wp-json\/wp\/v2\/tags?post=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}